{"id":1747,"date":"2016-04-08T10:11:28","date_gmt":"2016-04-08T10:11:28","guid":{"rendered":"https:\/\/coolrooms.com\/palaciovillapanes\/?p=1747"},"modified":"2016-04-08T10:11:28","modified_gmt":"2016-04-08T10:11:28","slug":"feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta","status":"publish","type":"post","link":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/","title":{"rendered":"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta!"},"content":{"rendered":"<p><a href=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/image_content_17168909_20150723145203.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-1749\" src=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/image_content_17168909_20150723145203-300x177.jpg\" alt=\"image_content_17168909_20150723145203\" width=\"300\" height=\"177\" \/><\/a><br \/>\nEste a\u00f1o la Fiesta Grande de Sevilla, la Feria de Abril, dar\u00e1 comienzo el lunes 11 a las 00:00 horas con el tradicional \u2018alumbrao\u2019 de la majestuosa \u2018Portada\u2019 de acceso al \u2018Real\u2019 y finalizar\u00e1 el domingo 17 a las 00:00 de la noche con fuegos artificiales. \u00bfQu\u00e9 te parece unirte a la diversi\u00f3n y descansar en el Palacio de Villapan\u00e9s, el mejor hotel de cinco estrellas de Sevilla? <!--more--> Uno de los momentos m\u00e1s emocionantes para los sevillanos en la <a href=\"https:\/\/bit.ly\/1zn9lWr\"><strong>Feria de Abril<\/strong><\/a> es la \u2018Prueba del alumbrado\u2019. El \u2018pistoletazo de salida\u2019 de la Feria, cuando 350.000 bombillas y farolillos se encienden a la vez para iluminar la \u2018Portada\u2019 y todo el \u2018Real\u2019, un enorme recinto ubicado en el barrio de los Remedios, donde se sit\u00faan las atracciones y las m\u00e1s de 1.000 casetas particulares y p\u00fablicas. El m\u00e1gico lugar donde se desarrolla el \u2018sarao\u2019, se come \u2018de maravilla\u2019, se bebe \u2018en demas\u00eda\u2019 y se baila \u2018en compa\u00f1\u00eda\u2019 a ritmo de palmas y sevillanas. Todos los a\u00f1os a las 00:00 horas miles de sevillanos y turistas se dan cita en la \u2018Portada\u2019 para ver el curioso espect\u00e1culo del \u2018<strong>alumbrao<\/strong>\u2019. Esta impresionante p\u00f3rtico construido al efecto cada a\u00f1o, alcanzar\u00e1 nada menos que 50 metros de altura y resplandecer\u00e1 a esa se\u00f1alada hora con sus m\u00e1s de 25.000 bombillas para anunciar el inicio de la Feria. Este a\u00f1o la \u2018<strong>Portada<\/strong>\u2019 es un homenaje a la <strong>danza<\/strong> y su dise\u00f1o ha corrido a cargo del dise\u00f1ador gr\u00e1fico Eduardo Mor\u00f3n, que se ha inspirado en el Pabell\u00f3n de Argentina de la Exposici\u00f3n Iberoamericana de 1929, situado junto al muelle de las Delicias. Un precioso y original edificio, que mezcla el estilo colonial peruano y boliviano con el neobarroco y es la sede del Conservatorio Superior de Danza de Sevilla Antonio Ruz Soler. Adem\u00e1s, su autor ha querido conmemorar en la \u2018Portada\u2019 dos importantes efem\u00e9rides que tienen lugar en 2016: el cuarto centenario de la muerte del escritor Miguel de Cervantes y el 750 aniversario de la Parroquia de Santa Ana de Triana. Esa misma noche tiene lugar otra famosa e ineludible costumbre para los sevillanos: la cena del \u2018<strong>pesca\u00edto<\/strong>\u2019, en la que los socios de las casetas se visten con sus mejores galas para una especial cena de \u2018mesa y mantel\u2019 a base de los mejores y crujientes pesca\u00edtos fritos. Un \u2018manjar de dioses\u2019 que te invitamos pruebes del \u2018<strong>Men\u00fa Especial Feria de Abril<\/strong>\u2019 de nuestro restaurante Los Rincones del Marqu\u00e9s. Reserva mesa en cualquiera de las estancias del Hotel Palacio Villapan\u00e9s que te tendremos preparadas para la ocasi\u00f3n. Te encantar\u00e1 pasar todo un d\u00eda en la Feria caminando sobre la amarilla arena de albero entre atracciones y casetas, disfrutando de la alegr\u00eda del ambiente y la simpat\u00eda de la gente, de la m\u00fasica y el baile, admirando el colorido de los trajes de flamenca, los coches de caballos, los jinetes y sus amazonas\u2026 Y a las 5 de la tarde, como en Inglaterra a la hora del t\u00e9, toca corrida de toros en la <strong>Maestranza<\/strong>. Un exhibici\u00f3n taurina que, al menos, debes ver una vez en la vida y que este a\u00f1o contar\u00e1 con un plantel de toreros de primera categor\u00eda, como Morante de la Puebla, Jos\u00e9 Mar\u00eda Manzanares, Ponce, El Juli o Castella&#8230; Eso s\u00ed, si no te gusta el arte del toreo puedes admirar el interesante museo sito en la misma plaza de toros. Pregunta en la <strong>recepci\u00f3n del Hotel Palacio Villapan\u00e9s<\/strong> c\u00f3mo conseguir entradas para los toros, c\u00f3mo llegar a la Feria, qu\u00e9 actividades puedes hacer cada d\u00eda, qu\u00e9 vestimenta y calzado es el m\u00e1s recomendable y qu\u00e9 precauciones debes tener para pasar unos d\u00edas de fiesta estupendos&#8230; Ten en cuenta que hay horas del d\u00eda en las que hay menos gente y visitantes en muchos de los monumentos y barrios sevillanos que deber\u00edas visitar, como los de Santa Cruz, Triana y el de la Macarena.<br \/>\n<a href=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/feria-abril-faroli\u00f1\u00f1os.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-1750\" src=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/feria-abril-faroli\u00f1\u00f1os-300x187.jpg\" alt=\"feria abril faroli\u00f1\u00f1os\" width=\"300\" height=\"187\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o la Fiesta Grande de Sevilla, la Feria de Abril, dar\u00e1 comienzo el lunes 11 a las 00:00 horas con el tradicional \u2018alumbrao\u2019 de la majestuosa \u2018Portada\u2019 de acceso al \u2018Real\u2019 y finalizar\u00e1 el domingo 17 a las 00:00 de la noche con fuegos artificiales. \u00bfQu\u00e9 te parece unirte a la diversi\u00f3n y descansar [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":2058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1184,1183,1176,1,1193],"tags":[1220,1342,1343,1344],"class_list":["post-1747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-hotel","category-paseos","category-sevilla","category-sin-categorizar","category-tapeo","tag-feria-de-abril","tag-pescaito","tag-portada","tag-toros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta! - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta! - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\" \/>\n<meta property=\"og:description\" content=\"Este a\u00f1o la Fiesta Grande de Sevilla, la Feria de Abril, dar\u00e1 comienzo el lunes 11 a las 00:00 horas con el tradicional \u2018alumbrao\u2019 de la majestuosa \u2018Portada\u2019 de acceso al \u2018Real\u2019 y finalizar\u00e1 el domingo 17 a las 00:00 de la noche con fuegos artificiales. \u00bfQu\u00e9 te parece unirte a la diversi\u00f3n y descansar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/palaciodevillapanes\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-08T10:11:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/04\/feria-abril-farolin\u0303n\u0303os.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"laura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"laura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/\"},\"author\":{\"name\":\"laura\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/person\\\/79b0c00e60a0df35b4915181f65ce9ec\"},\"headline\":\"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta!\",\"datePublished\":\"2016-04-08T10:11:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/\"},\"wordCount\":688,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/04\\\/feria-abril-farolin\u0303n\u0303os.jpg\",\"keywords\":[\"Feria de Abril\",\"pesca\u00edto\",\"Portada\",\"toros\"],\"articleSection\":[\"El Hotel\",\"Paseos\",\"Sevilla\",\"Sin categorizar\",\"Tapeo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/\",\"name\":\"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta! - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/04\\\/feria-abril-farolin\u0303n\u0303os.jpg\",\"datePublished\":\"2016-04-08T10:11:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/04\\\/feria-abril-farolin\u0303n\u0303os.jpg\",\"contentUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/04\\\/feria-abril-farolin\u0303n\u0303os.jpg\",\"width\":960,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#website\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\",\"name\":\"Hotel Palacio Villapan\u00e9s Sevilla\",\"description\":\"CoolRooms |\u00a0El lujo de dormir en un Palacio\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\",\"name\":\"Palacio Villapanes\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/logo-palacio-dark.png\",\"contentUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/logo-palacio-dark.png\",\"width\":300,\"height\":233,\"caption\":\"Palacio Villapanes\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/palaciodevillapanes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/palaciovillapanes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hotel-palacio-de-villapans\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/person\\\/79b0c00e60a0df35b4915181f65ce9ec\",\"name\":\"laura\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/author\\\/laura\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta! - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/","og_locale":"es_ES","og_type":"article","og_title":"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta! - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","og_description":"Este a\u00f1o la Fiesta Grande de Sevilla, la Feria de Abril, dar\u00e1 comienzo el lunes 11 a las 00:00 horas con el tradicional \u2018alumbrao\u2019 de la majestuosa \u2018Portada\u2019 de acceso al \u2018Real\u2019 y finalizar\u00e1 el domingo 17 a las 00:00 de la noche con fuegos artificiales. \u00bfQu\u00e9 te parece unirte a la diversi\u00f3n y descansar [&hellip;]","og_url":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/","og_site_name":"Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","article_publisher":"https:\/\/www.facebook.com\/palaciodevillapanes\/","article_published_time":"2016-04-08T10:11:28+00:00","og_image":[{"width":960,"height":599,"url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/04\/feria-abril-farolin\u0303n\u0303os.jpg","type":"image\/jpeg"}],"author":"laura","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"laura","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/#article","isPartOf":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/"},"author":{"name":"laura","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/person\/79b0c00e60a0df35b4915181f65ce9ec"},"headline":"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta!","datePublished":"2016-04-08T10:11:28+00:00","mainEntityOfPage":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/"},"wordCount":688,"commentCount":0,"publisher":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/#primaryimage"},"thumbnailUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/04\/feria-abril-farolin\u0303n\u0303os.jpg","keywords":["Feria de Abril","pesca\u00edto","Portada","toros"],"articleSection":["El Hotel","Paseos","Sevilla","Sin categorizar","Tapeo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/","url":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/","name":"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta! - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","isPartOf":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/#primaryimage"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/#primaryimage"},"thumbnailUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/04\/feria-abril-farolin\u0303n\u0303os.jpg","datePublished":"2016-04-08T10:11:28+00:00","breadcrumb":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/#primaryimage","url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/04\/feria-abril-farolin\u0303n\u0303os.jpg","contentUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/04\/feria-abril-farolin\u0303n\u0303os.jpg","width":960,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/feria-de-abril-2016-en-sevilla-que-lujo-de-fiesta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolrooms.com\/palaciovillapanes\/"},{"@type":"ListItem","position":2,"name":"Feria de Abril 2016 en Sevilla \u00a1Qu\u00e9 lujo de fiesta!"}]},{"@type":"WebSite","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#website","url":"https:\/\/coolrooms.com\/palaciovillapanes\/","name":"Hotel Palacio Villapan\u00e9s Sevilla","description":"CoolRooms |\u00a0El lujo de dormir en un Palacio","publisher":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolrooms.com\/palaciovillapanes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization","name":"Palacio Villapanes","url":"https:\/\/coolrooms.com\/palaciovillapanes\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/logo\/image\/","url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2022\/06\/logo-palacio-dark.png","contentUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2022\/06\/logo-palacio-dark.png","width":300,"height":233,"caption":"Palacio Villapanes"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/palaciodevillapanes\/","https:\/\/www.instagram.com\/palaciovillapanes\/","https:\/\/www.linkedin.com\/company\/hotel-palacio-de-villapans"]},{"@type":"Person","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/person\/79b0c00e60a0df35b4915181f65ce9ec","name":"laura","url":"https:\/\/coolrooms.com\/palaciovillapanes\/author\/laura\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/posts\/1747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/comments?post=1747"}],"version-history":[{"count":0,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/posts\/1747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/media\/2058"}],"wp:attachment":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/media?parent=1747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/categories?post=1747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/tags?post=1747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}