{"id":1401,"count":1,"description":"","link":"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/","name":"cumplea\u00f1os","slug":"cumpleanos-2","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>cumplea\u00f1os archivos - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cumplea\u00f1os archivos - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2017\/06\/logo-palacio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4001\" \/>\n\t<meta property=\"og:image:height\" content=\"2251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/category\\\/cumpleanos-2\\\/\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/category\\\/cumpleanos-2\\\/\",\"name\":\"cumplea\u00f1os archivos - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/category\\\/cumpleanos-2\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/category\\\/cumpleanos-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cumplea\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#website\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\",\"name\":\"Hotel Palacio Villapan\u00e9s Sevilla\",\"description\":\"CoolRooms |\u00a0El lujo de dormir en un Palacio\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\",\"name\":\"Palacio Villapanes\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/logo-palacio-dark.png\",\"contentUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/logo-palacio-dark.png\",\"width\":300,\"height\":233,\"caption\":\"Palacio Villapanes\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/palaciodevillapanes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/palaciovillapanes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hotel-palacio-de-villapans\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cumplea\u00f1os archivos - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/","og_locale":"es_ES","og_type":"article","og_title":"cumplea\u00f1os archivos - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","og_url":"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/","og_site_name":"Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","og_image":[{"width":4001,"height":2251,"url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2017\/06\/logo-palacio.jpg","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/","url":"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/","name":"cumplea\u00f1os archivos - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","isPartOf":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#website"},"breadcrumb":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/category\/cumpleanos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolrooms.com\/palaciovillapanes\/"},{"@type":"ListItem","position":2,"name":"cumplea\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#website","url":"https:\/\/coolrooms.com\/palaciovillapanes\/","name":"Hotel Palacio Villapan\u00e9s Sevilla","description":"CoolRooms |\u00a0El lujo de dormir en un Palacio","publisher":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolrooms.com\/palaciovillapanes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization","name":"Palacio Villapanes","url":"https:\/\/coolrooms.com\/palaciovillapanes\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/logo\/image\/","url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2022\/06\/logo-palacio-dark.png","contentUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2022\/06\/logo-palacio-dark.png","width":300,"height":233,"caption":"Palacio Villapanes"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/palaciodevillapanes\/","https:\/\/www.instagram.com\/palaciovillapanes\/","https:\/\/www.linkedin.com\/company\/hotel-palacio-de-villapans"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/categories\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-json\/wp\/v2\/posts?categories=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}