{"id":3485,"date":"2016-02-27T15:17:25","date_gmt":"2016-02-27T15:17:25","guid":{"rendered":"https:\/\/coolrooms.com\/palaciovillapanes\/?p=3485\/"},"modified":"2016-02-27T11:18:32","modified_gmt":"2016-02-27T11:18:32","slug":"fiesta-de-andalucia-fiesta-de-la-alegria-3","status":"publish","type":"post","link":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/","title":{"rendered":"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda"},"content":{"rendered":"<p><div id=\"attachment_1702\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/bandera-andaluza.jpg\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-1702\" class=\"size-medium wp-image-1702\" src=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/bandera-andaluza-300x201.jpg\" alt=\"Escudo bandera Andaluc\u00eda: 'Andaluc\u00eda por s\u00ed, para Espa\u00f1a y la Humanidad'\" width=\"300\" height=\"201\" \/><\/a><p id=\"caption-attachment-1702\" class=\"wp-caption-text\">Escudo bandera Andaluc\u00eda: &lsquo;Andaluc\u00eda por s\u00ed, para Espa\u00f1a y la Humanidad&rsquo;<\/p><\/div><br \/>\nEl 28 de febrero es el \u2018D\u00eda de la Comunidad de Andaluc\u00eda\u2019. Una fecha se\u00f1alada en el coraz\u00f3n y en el calendario de los andaluces y, muy especialmente, en el de los sevillanos, porque se celebra el d\u00eda de su identidad como comunidad aut\u00f3noma, de la personalidad que la diferencia de otras regiones espa\u00f1olas. Ven a Sevilla y as\u00f3mbrate de una ciudad engalanada para la ocasi\u00f3n y descubre el alegre temperamento que define a sus gentes.<!--more--><br \/>\nSi tienes la suerte de estar en Andaluc\u00eda el 28 de febrero podr\u00e1s disfrutar de un d\u00eda especial y festivo para los andaluces. Es la fecha del aniversario de la aprobaci\u00f3n en refer\u00e9ndum de la plena autonom\u00eda de esta comunidad aut\u00f3noma hist\u00f3rica del sur de Espa\u00f1a.<br \/>\n\u00a1Sal a la calle y emp\u00e1pate de <a href=\"https:\/\/bit.ly\/1GxYJE6\">Sevilla<\/a> ese d\u00eda! Avenidas y balcones se adornan con banderas verdes y blancas, que simbolizan la esperanza y la paz y que tienen en su centro un solemne escudo, que representa a H\u00e9rcules entre sus dos columnas con un significativo texto: &lsquo;Andaluc\u00eda por s\u00ed, para Espa\u00f1a y la Humanidad&rsquo;.<br \/>\nEn instituciones y plazas tienen lugar actos conmemorativos de su identidad, de su orgullo como andaluces, con entrega de medallas, premios, concursos de patios andaluces, de flamenco\u2026 Un d\u00eda que se ensalzan y se ponen en pr\u00e1ctica multitud de tradiciones en un agradable ambiente festivo y participativo para propios y extra\u00f1os.<br \/>\n\u00bfY por qu\u00e9 encontrar\u00e1s en esta tierra esa maravillosa hospitalidad y calidez humana? Porque son rasgos intr\u00ednsecos a la personalidad andaluza. Ante todo los andaluces y, especialmente, los sevillanos son personas abiertas, muy sociables, fabricantes de contagiosa alegr\u00eda, de buen sentido del humor: saben re\u00edrse con \u2018gracia\u2019 de las adversidades y con \u2018guasa\u2019 de s\u00ed mismos. Es decir, son gentes optimistas por naturaleza y trasmiten a los visitantes esa positividad que es tan necesaria para ser feliz.<br \/>\nEl <a href=\"https:\/\/bit.ly\/1Kq2nQn\">Palacio de Villapan\u00e9s<\/a> guarda celosamente entre sus muros la esencia m\u00e1s genuina del alma andaluza, con una construcci\u00f3n con tintes barrocos y mud\u00e9jares de magn\u00edfica elegancia y representatividad andaluza. El hotel, a la vez, esconde entre sus muros aut\u00e9nticos patios andaluces, rebosantes de flores y plantas que lo embellecen, lustran y templan el esp\u00edritu con el tintineo de sus fuentes&#8230;<br \/>\nEn su restaurante, <a href=\"https:\/\/bit.ly\/1DBDyyR\">Los Rincones del Marqu\u00e9s<\/a>, podr\u00e1s degustar platos t\u00edpicos de la gastronom\u00eda andaluza y mediterr\u00e1nea, pero te recomendamos que no dejes de seguir una de sus m\u00e1s conocidas costumbres de ese d\u00eda: pide para desayunar una \u2018humilde\u2019 pero sabrosa \u2018tosta de pan con aceite puro de oliva virgen\u2019, uno de los alimentos m\u00e1s sanos que existen y que, adem\u00e1s, es una aut\u00e9ntica delicia al paladar. \u00a1Un sencillo placer!<br \/>\nNo lo pienses m\u00e1s y conoce Andaluc\u00eda, Sevilla y nuestro Hotel Palacio de Villapan\u00e9s el 28 de febrero porque\u2026 \u00bfExiste un pueblo y una tierra m\u00e1s orgullosa de su tierra, sus costumbres y que sepa mejor disfrutar de la vida?<br \/>\n<a href=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/pan-y-aceite.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-1703\" src=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/pan-y-aceite-300x300.jpg\" alt=\"sliced bread with olive oil\" width=\"300\" height=\"300\" \/> <\/a><a href=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/PATIO-ENTRADA2.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-1704\" src=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/PATIO-ENTRADA2-300x225.jpg\" alt=\"PATIO ENTRADA\" width=\"300\" height=\"225\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 28 de febrero es el \u2018D\u00eda de la Comunidad de Andaluc\u00eda\u2019. Una fecha se\u00f1alada en el coraz\u00f3n y en el calendario de los andaluces y, muy especialmente, en el de los sevillanos, porque se celebra el d\u00eda de su identidad como comunidad aut\u00f3noma, de la personalidad que la diferencia de otras regiones espa\u00f1olas. Ven [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":2834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\" \/>\n<meta property=\"og:description\" content=\"El 28 de febrero es el \u2018D\u00eda de la Comunidad de Andaluc\u00eda\u2019. Una fecha se\u00f1alada en el coraz\u00f3n y en el calendario de los andaluces y, muy especialmente, en el de los sevillanos, porque se celebra el d\u00eda de su identidad como comunidad aut\u00f3noma, de la personalidad que la diferencia de otras regiones espa\u00f1olas. Ven [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/palaciodevillapanes\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-27T15:17:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2017\/06\/logo-palacio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4001\" \/>\n\t<meta property=\"og:image:height\" content=\"2251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"laura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"laura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/\"},\"author\":{\"name\":\"laura\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/person\\\/79b0c00e60a0df35b4915181f65ce9ec\"},\"headline\":\"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda\",\"datePublished\":\"2016-02-27T15:17:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/\"},\"wordCount\":555,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/\",\"name\":\"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-02-27T15:17:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/fiesta-de-andalucia-fiesta-de-la-alegria-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#website\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\",\"name\":\"Hotel Palacio Villapan\u00e9s Sevilla\",\"description\":\"CoolRooms |\u00a0El lujo de dormir en un Palacio\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\",\"name\":\"Palacio Villapanes\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/logo-palacio-dark.png\",\"contentUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/logo-palacio-dark.png\",\"width\":300,\"height\":233,\"caption\":\"Palacio Villapanes\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/palaciodevillapanes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/palaciovillapanes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hotel-palacio-de-villapans\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/person\\\/79b0c00e60a0df35b4915181f65ce9ec\",\"name\":\"laura\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/author\\\/laura\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/","og_locale":"fr_FR","og_type":"article","og_title":"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","og_description":"El 28 de febrero es el \u2018D\u00eda de la Comunidad de Andaluc\u00eda\u2019. Una fecha se\u00f1alada en el coraz\u00f3n y en el calendario de los andaluces y, muy especialmente, en el de los sevillanos, porque se celebra el d\u00eda de su identidad como comunidad aut\u00f3noma, de la personalidad que la diferencia de otras regiones espa\u00f1olas. Ven [&hellip;]","og_url":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/","og_site_name":"Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","article_publisher":"https:\/\/www.facebook.com\/palaciodevillapanes\/","article_published_time":"2016-02-27T15:17:25+00:00","og_image":[{"width":4001,"height":2251,"url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2017\/06\/logo-palacio.jpg","type":"image\/png"}],"author":"laura","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"laura","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/#article","isPartOf":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/"},"author":{"name":"laura","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/person\/79b0c00e60a0df35b4915181f65ce9ec"},"headline":"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda","datePublished":"2016-02-27T15:17:25+00:00","mainEntityOfPage":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/"},"wordCount":555,"commentCount":0,"publisher":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/#primaryimage"},"thumbnailUrl":"","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/","url":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/","name":"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","isPartOf":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/#primaryimage"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-02-27T15:17:25+00:00","breadcrumb":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/fiesta-de-andalucia-fiesta-de-la-alegria-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/"},{"@type":"ListItem","position":2,"name":"Fiesta de Andaluc\u00eda, fiesta de la alegr\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#website","url":"https:\/\/coolrooms.com\/palaciovillapanes\/","name":"Hotel Palacio Villapan\u00e9s Sevilla","description":"CoolRooms |\u00a0El lujo de dormir en un Palacio","publisher":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolrooms.com\/palaciovillapanes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization","name":"Palacio Villapanes","url":"https:\/\/coolrooms.com\/palaciovillapanes\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/logo\/image\/","url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2022\/06\/logo-palacio-dark.png","contentUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2022\/06\/logo-palacio-dark.png","width":300,"height":233,"caption":"Palacio Villapanes"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/palaciodevillapanes\/","https:\/\/www.instagram.com\/palaciovillapanes\/","https:\/\/www.linkedin.com\/company\/hotel-palacio-de-villapans"]},{"@type":"Person","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/person\/79b0c00e60a0df35b4915181f65ce9ec","name":"laura","url":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/author\/laura\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/posts\/3485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/comments?post=3485"}],"version-history":[{"count":0,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/posts\/3485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/media?parent=3485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/categories?post=3485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/tags?post=3485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}