{"id":3435,"date":"2016-06-17T10:11:42","date_gmt":"2016-06-17T10:11:42","guid":{"rendered":"https:\/\/coolrooms.com\/palaciovillapanes\/?p=3435\/"},"modified":"2022-06-08T11:53:31","modified_gmt":"2022-06-08T11:53:31","slug":"tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3","status":"publish","type":"post","link":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/","title":{"rendered":"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s"},"content":{"rendered":"<p><a href=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-1812\" src=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-300x200.jpg\" alt=\"CUADRO FLAMENCO EN SOLARIUM CON VISTAS DE NOCHE\" width=\"300\" height=\"200\" \/><\/a><br \/>\nLa XIX edici\u00f3n de la Bienal de Flamenco se celebra este a\u00f1o del 8 de septiembre al 2 de octubre. Como muchos otros grandes acontecimientos que tienen lugar en la ciudad de Sevilla, como la Semana Santa o la Feria de Abril, la Bienal tiene una repercusi\u00f3n tan importante a nivel nacional como internacional, que es dif\u00edcil encontrar habitaci\u00f3n en un hotel en esas fechas\u2026 Pero \u00bfSabes el porqu\u00e9 merece la pena venir a verla?<!--more--><br \/>\nCada dos a\u00f1os se celebra el festival de la Bienal de Flamenco de Sevilla, el m\u00e1s importante concurso y, a la vez, homenaje al flamenco en nuestro pa\u00eds. Adem\u00e1s, como todos los a\u00f1os viene con un <a href=\"https:\/\/bit.ly\/1tkPh6K\">programa<\/a> repleto de vistosos espect\u00e1culos, interesantes actividades y conferencias, ponencias culturales relacionadas e, incluso, trabajos de ense\u00f1anza del flamenco a los escolares sevillanos, para que conozcan y aprendan uno de los artes m\u00e1s diferenciadores de su tierra. Unas jornadas profesionales donde cientos de artistas y miles de aficionados provenientes de los m\u00e1s rec\u00f3nditos rincones del mundo y apasionados de este peculiar arte andaluz, se dan cita en este certamen de la capital hispalense en busca de sentir la fuerza y el sentimiento de un estilo musical pasional y distinto.<br \/>\nLa Bienal tiene programados nada menos que 66 espect\u00e1culos, que se distribuir\u00e1n entre los curtidos escenarios de los principales teatros de la ciudad, como La Maestranza, Alameda, Central y Lope de Vega. Y, tambi\u00e9n, se habilitan para este especial evento emblem\u00e1ticos espacios esc\u00e9nicos sevillanos como el Alc\u00e1zar de Sevilla, la iglesia de San Luis de los Franceses, el claustro del Convento de Santa Clara o el patio del antiguo Hotel Triana. Los patios de butacas se llenar\u00e1n de entusiastas ansiosos de escuchar y sentir el flamenco, el taconeo de los bailaores y bailaoras, el sonido de las guitarras&#8230;<br \/>\nLas magn\u00edficas galas contar\u00e1n con artistas consagrados del cante en estado puro, el baile flamenco y la <a href=\"https:\/\/bit.ly\/1tnWyzb\">guitarra espa\u00f1ola<\/a>, a los que se sumar\u00e1n un nutrido grupo de nuevas y j\u00f3venes promesas, que tratar\u00e1n de demostrar su val\u00eda y se reconozca su labor creativa. Sus aportaciones marcar\u00e1n las tendencias futuras que enriquecer\u00e1n este arte esc\u00e9nico. Una mezcla perfecta de venerados y veteranos artistas con el empuje de j\u00f3venes talentos, que har\u00e1n de su cante, baile y toque de guitarra espa\u00f1ola todo un espect\u00e1culo lleno de arte y sentimiento.<br \/>\nEste a\u00f1o se dan cita en este certamen un completo plantel de tres generaciones de artistas de la talla de Vicente Amigo, Pastora Galv\u00e1n, Jos\u00e9 Valencia, Isabel Bay\u00f3n, Rafael Riqueni, Tomatito, Estrella Morente, Carmen Linares, Antonio Canales, Marina Heredia, Pepe Habichuela, Bel\u00e9n Maya, Jos\u00e9 Acedo, Esperanza Fern\u00e1ndez, Gonzalo Rubalcaba, Manuel Parrilla, Merche Esmeralda, Milagros Menj\u00edbar, Ana Mar\u00eda Bueno, Manolo Mar\u00edn, Jos\u00e9 Galv\u00e1n, Roc\u00edo Marquez, Famhi Alqhai, Dani de Mor\u00f3n, Isabel Galv\u00e1n, Roc\u00edo M\u00e1rquez, Arc\u00e1ngel, Antonio Agujetas, Duquende, Pitingo, Taksim Tr\u00edo, Capullo de Jerez, Juana la del Pipa\u2026<br \/>\nY queremos hacer una menci\u00f3n especial para Isabel Bay\u00f3n, Premio Nacional de Danza, Roc\u00edo Molina, que promete un espect\u00e1culo muy especial y diferente sin hora de finalizaci\u00f3n y el m\u00edtico e inigualable Jos\u00e9 Merc\u00e9, que grabar\u00e1 en la funci\u00f3n de despedida un esperad\u00edsimo disco en directo.<br \/>\nUna oportunidad de disfrutar a la vez del flamenco tradicional, arraigado en las ra\u00edces m\u00e1s profundas de Andaluc\u00eda, con las propuestas de vanguardia que consagran al flamenco como un estilo musical vivo, culmen de la creatividad, de la evoluci\u00f3n constante y la fusi\u00f3n y experimentaci\u00f3n arriesgada con otras disciplinas musicales.<br \/>\nTambi\u00e9n, en el <a href=\"https:\/\/bit.ly\/1Kq2nQn\">Hotel Palacio Villapan\u00e9s<\/a>, le damos un gran valor al flamenco, por ser una expresi\u00f3n cultural y musical del cante y baile de nuestra tierra andaluza. Una \u00edntima raz\u00f3n por la que queremos compartirlo con nuestros hu\u00e9spedes para que lo conozcan y lo disfruten. Por todo ello, los jueves y viernes ofrecemos cenas especiales con baile flamenco en nuestro cuidado patio andaluz de los Naranjos.<br \/>\nNo se te olvide <a href=\"https:\/\/bit.ly\/1NX2Wrq\">reservar<\/a> tu mesa en nuestro restaurante Los Rincones del Marqu\u00e9s y disfruta del arte flamenco con sonoros \u2018ol\u00e9s\u2019 y del arte de la gastronom\u00eda en un marco incomparable como es un aut\u00e9ntico palacio del siglo XVIII, donde descubrir\u00e1s el \u2018duende\u2019 y la magia del flamenco.<br \/>\n<a href=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/laBienal2016_cartel.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-1814\" src=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/laBienal2016_cartel-213x300.jpg\" alt=\"laBienal2016_cartel\" width=\"213\" height=\"300\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La XIX edici\u00f3n de la Bienal de Flamenco se celebra este a\u00f1o del 8 de septiembre al 2 de octubre. Como muchos otros grandes acontecimientos que tienen lugar en la ciudad de Sevilla, como la Semana Santa o la Feria de Abril, la Bienal tiene una repercusi\u00f3n tan importante a nivel nacional como internacional, que [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":13413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\" \/>\n<meta property=\"og:description\" content=\"La XIX edici\u00f3n de la Bienal de Flamenco se celebra este a\u00f1o del 8 de septiembre al 2 de octubre. Como muchos otros grandes acontecimientos que tienen lugar en la ciudad de Sevilla, como la Semana Santa o la Feria de Abril, la Bienal tiene una repercusi\u00f3n tan importante a nivel nacional como internacional, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/palaciodevillapanes\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-17T10:11:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-08T11:53:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/06\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"laura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"laura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/\"},\"author\":{\"name\":\"laura\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/person\\\/79b0c00e60a0df35b4915181f65ce9ec\"},\"headline\":\"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s\",\"datePublished\":\"2016-06-17T10:11:42+00:00\",\"dateModified\":\"2022-06-08T11:53:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/\"},\"wordCount\":774,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/06\\\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/\",\"name\":\"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/06\\\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg\",\"datePublished\":\"2016-06-17T10:11:42+00:00\",\"dateModified\":\"2022-06-08T11:53:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/06\\\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/06\\\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#website\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\",\"name\":\"Hotel Palacio Villapan\u00e9s Sevilla\",\"description\":\"CoolRooms |\u00a0El lujo de dormir en un Palacio\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#organization\",\"name\":\"Palacio Villapanes\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/logo-palacio-dark.png\",\"contentUrl\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/logo-palacio-dark.png\",\"width\":300,\"height\":233,\"caption\":\"Palacio Villapanes\"},\"image\":{\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/palaciodevillapanes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/palaciovillapanes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hotel-palacio-de-villapans\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/#\\\/schema\\\/person\\\/79b0c00e60a0df35b4915181f65ce9ec\",\"name\":\"laura\",\"url\":\"https:\\\/\\\/coolrooms.com\\\/palaciovillapanes\\\/fr\\\/author\\\/laura\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/","og_locale":"fr_FR","og_type":"article","og_title":"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","og_description":"La XIX edici\u00f3n de la Bienal de Flamenco se celebra este a\u00f1o del 8 de septiembre al 2 de octubre. Como muchos otros grandes acontecimientos que tienen lugar en la ciudad de Sevilla, como la Semana Santa o la Feria de Abril, la Bienal tiene una repercusi\u00f3n tan importante a nivel nacional como internacional, que [&hellip;]","og_url":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/","og_site_name":"Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","article_publisher":"https:\/\/www.facebook.com\/palaciodevillapanes\/","article_published_time":"2016-06-17T10:11:42+00:00","article_modified_time":"2022-06-08T11:53:31+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/06\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg","type":"image\/jpeg"}],"author":"laura","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"laura","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/#article","isPartOf":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/"},"author":{"name":"laura","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/person\/79b0c00e60a0df35b4915181f65ce9ec"},"headline":"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s","datePublished":"2016-06-17T10:11:42+00:00","dateModified":"2022-06-08T11:53:31+00:00","mainEntityOfPage":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/"},"wordCount":774,"commentCount":0,"publisher":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/#primaryimage"},"thumbnailUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/06\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/","url":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/","name":"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s - Hotel CoolRooms Palacio Villapan\u00e9s Sevilla","isPartOf":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/#primaryimage"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/#primaryimage"},"thumbnailUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/06\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg","datePublished":"2016-06-17T10:11:42+00:00","dateModified":"2022-06-08T11:53:31+00:00","breadcrumb":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/#primaryimage","url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/06\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg","contentUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2016\/06\/CUADRO-FLAMENCO-EN-SOLARIUM-CON-VISTAS-DE-NOCHE-1024x683-1.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/tienes-cita-en-septiembre-con-la-bienal-de-flamenco-sevilla-y-el-hotel-palacio-villapanes-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienes cita en septiembre con la Bienal de Flamenco, Sevilla y el Hotel Palacio Villapan\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#website","url":"https:\/\/coolrooms.com\/palaciovillapanes\/","name":"Hotel Palacio Villapan\u00e9s Sevilla","description":"CoolRooms |\u00a0El lujo de dormir en un Palacio","publisher":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolrooms.com\/palaciovillapanes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#organization","name":"Palacio Villapanes","url":"https:\/\/coolrooms.com\/palaciovillapanes\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/logo\/image\/","url":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2022\/06\/logo-palacio-dark.png","contentUrl":"https:\/\/coolrooms.com\/palaciovillapanes\/wp-content\/uploads\/sites\/7\/2022\/06\/logo-palacio-dark.png","width":300,"height":233,"caption":"Palacio Villapanes"},"image":{"@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/palaciodevillapanes\/","https:\/\/www.instagram.com\/palaciovillapanes\/","https:\/\/www.linkedin.com\/company\/hotel-palacio-de-villapans"]},{"@type":"Person","@id":"https:\/\/coolrooms.com\/palaciovillapanes\/#\/schema\/person\/79b0c00e60a0df35b4915181f65ce9ec","name":"laura","url":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/author\/laura\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/posts\/3435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/comments?post=3435"}],"version-history":[{"count":0,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/posts\/3435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/media\/13413"}],"wp:attachment":[{"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/media?parent=3435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/categories?post=3435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coolrooms.com\/palaciovillapanes\/fr\/wp-json\/wp\/v2\/tags?post=3435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}